{"id":106,"count":0,"description":"","link":"https:\/\/www.waffenpflegewelt.de\/ratgeber\/thema\/ausruestung\/","name":"Aur\u00fcstung","slug":"ausruestung","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.waffenpflegewelt.de\/ratgeber\/wp-json\/wp\/v2\/categories\/106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waffenpflegewelt.de\/ratgeber\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.waffenpflegewelt.de\/ratgeber\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.waffenpflegewelt.de\/ratgeber\/wp-json\/wp\/v2\/posts?categories=106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}